{"id":1178,"date":"2020-05-22T18:39:45","date_gmt":"2020-05-22T18:39:45","guid":{"rendered":"https:\/\/www.museumswelt.de\/blog\/?p=1178"},"modified":"2020-06-23T20:55:20","modified_gmt":"2020-06-23T20:55:20","slug":"verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020","status":"publish","type":"post","link":"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/","title":{"rendered":"&#8222;Verr\u00fcckt nach<br> Angelika Kauffmann&#8220;<br>verl\u00e4ngert bis<br>20. September 2020"},"content":{"rendered":"\n<p class=\"has-normal-font-size\"><span class=\"has-inline-color\" style=\"color:#070a4b\"><strong>Pressemitteilung Museum Kunstpalast D\u00fcsseldorf, Mai 2020<\/strong><\/span><\/p>\n\n\n\n<p class=\"has-text-align-center\"><span class=\"has-inline-color\" style=\"color:#070a4b\">KUNSTPALAST<br>Ehrenhof 4-5, 40479 D\u00fcsseldorf<br>www.kunstpalast.de<\/span><\/p>\n\n\n<p>Mit \u201eVerr\u00fcckt nach Angelika Kauffmann\u201c widmet der Kunstpalast der ber\u00fchmtesten K\u00fcnstlerin im Zeitalter der Aufkl\u00e4rung und Empfindsamkeit eine gro\u00dfe \u00dcberblicksausstellung. Unter den etwa 100 Gem\u00e4lden, Zeichnungen und Skulpturen werden etliche erstmals \u00f6ffentlich gezeigt. Auch Druckgrafik und Kunsthandwerk nach Motiven der K\u00fcnstlerin lassen eine Zeit aufleben, in der es hie\u00df: \u201eThe whole World is angelicamad\u201c \u2013\u201eDie ganze Welt ist verr\u00fcckt nach Angelika\u201c.<\/p>\n\n\n<!--more-->\n\n\n\n<p>Die von ihrem Zeitgenossen J. G. Herder als die \u201evielleicht kultivierteste Frau in Europa\u201c beschriebene Angelika Kauffmann (Chur 1741\u20131807 Rom) war eine europaweit vernetzte und weltoffene K\u00fcnstlerin des Klassizismus. Anerkannt f\u00fcr ihr k\u00fcnstlerisches Talent und ihre umfassende Bildung, durchlief sie eine f\u00fcr Frauen damals beispiellose Karriere. Schon in jungen Jahren als musisches Wunderkind gepriesen, wurde Kauffmann auch fr\u00fch f\u00fcr ihre Malerei bewundert. Nach ihrer k\u00fcnstlerischen Aus\u00adbildung in Italien in den Jahren 1759 bis 1766 erlangte sie in London, protegiert vom englischen Adel, als Historien- und Bildnismalerin gro\u00dfe Ber\u00fchmtheit. Nach f\u00fcnfzehn produktiven Jahren in London er\u00f6ffnete die gefragte Portr\u00e4tistin 1782 in Rom eines der bestbesuchten Ateliers ihrer Zeit. Kauffmanns Weltgewandtheit, ihr Gesch\u00e4ftssinn und der von ihr gef\u00fchrte k\u00fcnstlerische Salon, in dem sich ein internationaler Kreis von Auftraggebern und Freunden traf, machten sie zu einer europ\u00e4ischen Gr\u00f6\u00dfe.<\/p>\n\n\n\n<p>\u201eIch freue mich, dass wir diese zu ihrer Zeit weltbekannte Malerin im Zusammenhang mit neuen Forschungserkenntnissen zeigen k\u00f6nnen\u201c, betont Felix Kr\u00e4mer, General\u00addirektor Kunstpalast. \u201eKauffmanns kunsthistorischer Stellenwert wird auch dadurch unterstrichen, dass die Ausstellung anschlie\u00dfend in der Royal Academy of Arts in London zu sehen sein wird. Die K\u00fcnstlerin, die 1768 zu den Gr\u00fcndungsmitgliedern dieser traditionsreichen Institution geh\u00f6rte, wird dort erstmals mit einer eigenen Werkschau gew\u00fcrdigt.\u201c<\/p>\n\n\n\n<p>Angelika Kauffmann galt als \u201eRaffael unter den K\u00fcnstlerinnen\u201c, so Giovanni G. de Rossi in seinen noch zu Lebzeiten \u00fcber Kauffmann ver\u00f6ffentlichten Schriften. Von Angeh\u00f6\u00adrigen der Hocharistokratie, des Adels und B\u00fcrgertums sowie der geistigen Elite Europas erhielt sie zahlreiche Auftr\u00e4ge. Zu ihren M\u00e4zenen geh\u00f6rten unter anderem Joseph II., Kaiser von \u00d6sterreich, und die russische Zarin Katharina die Gro\u00dfe.<\/p>\n\n\n\n<p>\u201eViele von Kauffmanns Werken galten als stilpr\u00e4gend und l\u00f6sten einen regelrechten \u201aKauffmann-Kult\u2018 aus\u201c, hebt die Kuratorin Bettina Baumg\u00e4rtel hervor. \u201eIhre wegweisen\u00adden Historienbilder, ihre glanzvollen Portr\u00e4ts, ihre literarischen und mythologischen Szenen geben einen umfassenden Einblick in eine Epoche, die gleicherma\u00dfen von der Vernunft wie auch von der Empfindsamkeit gepr\u00e4gt war.\u201c<\/p>\n\n\n\n<p>Noch vor Erscheinen des Werkverzeichnisses, das die Kuratorin im Rahmen des Angelika Kauffmann Research Project (AKRP) vorbereitet, stellt die Ausstellung Ergebnisse ihrer Forschung vor und beleuchtet Fragen zur Selbstinszenierung der K\u00fcnstlerin sowie zu dem Frauen- oder M\u00e4nnerbild, das Kauffmann in ihren Portr\u00e4ts und Historienbildern pr\u00e4gte.<\/p>\n\n\n\n<p>Der Rundgang durch die in neun Kapitel gegliederte Ausstellung kennzeichnet die \u00f6sterreichisch-schweizerische K\u00fcnstlerin als Europ\u00e4erin \u201eavant la lettre\u201c und thema\u00adtisiert zu Beginn ihre Ausbildungszeit in Italien. Ihr dort entstandenes Bildnis des Altertumsforschers Johann Joachim Winckelmann (1764, Kunsthaus Z\u00fcrich) f\u00f6rdert die europaweite Bekanntheit der jungen Malerin.<\/p>\n\n\n\n<p>Der anschlie\u00dfende Ausstellungsbereich <em>Bl\u00fctezeit in England<\/em> fokussiert die Strategien der gesch\u00e4ftst\u00fcchtigen Malerin im Umgang mit den Angeh\u00f6rigen des englischen Hofes und deren Patronage. Das Kapitel <em>Die Portr\u00e4tmalerin als Modemacherin<\/em> zeigt, dass sich Kauffmann neben den englischen Portr\u00e4tisten Joshua Reynolds und Thomas Gainsborough zwischen 1766 und 1781 zur gefragtesten Malerin auf dem britischen Portr\u00e4tmarkt entwickeln konnte. \u201eDer englischen Kunst gab sie wichtige Impulse und trug zudem zur Erneuerung der Historienmalerei bei\u201c, erl\u00e4utert Bettina Baumg\u00e4rtel. \u201eIndem sie Reynolds Konzept des ,historicizing portrait\u2019, zu Deutsch Rollenbildnis, adaptierte, die Van-Dyck- oder Orient-Mode aufgriff und die antikisierende Kleidung zur Mode erhob, galten ihre Portr\u00e4ts als besonders \u201afashionable\u2018.\u201c Junge Frauen der h\u00f6heren Gesellschaft und einflussreiche Vertreterinnen des Hofes geh\u00f6rten zu den ersten, die Kauffmann in England portr\u00e4tierte.<\/p>\n\n\n\n<p>Ein weiteres Kapitel ist den in England entstandenen Historiengem\u00e4lden gewidmet. Dank ihres Sinns f\u00fcr Marketing, Image- und Kundenpflege war Kauffmann so erfolg\u00adreich, dass sie sich einem eigenen k\u00fcnstlerischen Interesse widmen konnte: der Historienmalerei. Mit ihren einfigurigen Historienbildern entwickelte sie sich zu einer Wegbereiterin der Empfindsamkeit.<\/p>\n\n\n\n<p>Um der gro\u00dfen Nachfrage ihrer Kunst gerecht zu werden, bediente sich die Malerin der Reproduktionsgrafik: Kupferstecher aus ganz Europa trugen zur Popularisierung und massenhaften Verbreitung von Kauffmanns Kunst bei. Dar\u00fcber hinaus fanden ihre Motive sich ab den 1770er-Jahren als Dekor auf Porzellan, F\u00e4chern, Tabakdosen, Tapeten und Textilien wieder.<\/p>\n\n\n\n<p>Das Herzst\u00fcck der Ausstellung im Kunstpalast bilden die vier Deckengem\u00e4lde, welche die Malerin 1778 bis 1780 f\u00fcr die Royal Academy of Arts, gefertigt hat. Erstmals werden diese Hauptwerke, die damals im Somerset House angebracht wurden, sich aber heute im Vestib\u00fcl des Burlington House befinden, au\u00dferhalb von London ausgestellt. Das Kapitel problematisiert das Verbot f\u00fcr K\u00fcnstlerinnen, an Akademien ausgebildet zu werden und zeigt die au\u00dfergew\u00f6hnliche Situation von Angelika Kauffmann, ausnahmsweise als Frau zum Mitglied an f\u00fcnf Kunstakademien ernannt worden zu sein.<\/p>\n\n\n\n<p>Nach ihrer Heirat mit dem venezianischen Vedutenmaler Antonio Zucchi 1781 kehrte Kauffmann nach Rom zur\u00fcck. Sowohl ihr Vater als auch ihr Mann arbeiteten ihr als Assistenten zu. Das Kapitel <em>Rom, Residenz der K\u00fcnste<\/em> beleuchtet Kauffmanns Bezie\u00adhungen zu neuen, h\u00f6chsten Kreisen des Adels und zu den K\u00fcnstlerkollegen wie Antonio Canova. In dieser Zeit malte die K\u00fcnstlerin ihre bedeutendsten Historien\u00adgem\u00e4lde, einige davon werden erstmals gezeigt. In diesen werden Frauen als Heldin\u00adnen in den Mittelpunkt gestellt. Die starken Frauenfiguren pr\u00e4gten entscheidend das neue Weiblichkeitsideal der Aufkl\u00e4rung.<\/p>\n\n\n\n<p>Einen weiteren H\u00f6hepunkt der Ausstellung bildet das Kapitel <em>Der<\/em> <em>Parnass der Musen.<\/em> Hier werden die besten Beispiele expressiver Bildnisse aus der Hand der K\u00fcnstlerin vorge\u00adstellt, in denen Schauspielerinnen und Dichterinnen, die im Salon von Kauffmann aufgetreten sind, als Musen portr\u00e4tiert wurden.<\/p>\n\n\n\n<p>Der Rundgang schlie\u00dft mit einem Blick auf Kauffmanns <em>Religi\u00f6ses Sp\u00e4twerk<\/em>. Gezeigt wird die letzte religi\u00f6se Historie <em>David und Nathan <\/em>(um 1806\/07, Bregenz, voralberg museum), die w\u00e4hrend ihres prunkvollen Begr\u00e4bnisses in Rom mit ihrem Sarg mit\u00adgef\u00fchrt wurde. In diesem Gem\u00e4lde zeigt sich exemplarisch Kauffmanns R\u00fcckbesin\u00adnung auf die Meister des italienischen Barock.<\/p>\n\n\n\n<p>Den Ruhm, den Angelika Kauffmann am Ende ihres Schaffens erlangt hatte, ist an zwei in der Ausstellung pr\u00e4sentierten Bildnis-B\u00fcsten ablesbar, die ihr zu Ehren f\u00fcr die Pr\u00e4sentation im Pantheon und in der Walhalla geschaffen wurden.<\/p>\n\n\n\n<p>Dank der gro\u00dfen Kollegialit\u00e4t der an der Ausstellung beteiligten Museen, Galerien und privaten Leihgeber ist es m\u00f6glich, die Werkschau von Angelika Kauffmann in D\u00fcsseldorf bis 20. September 2020 zu pr\u00e4sentieren. Dieses gilt auch f\u00fcr die Leihgabe von Queen Elizabeth II. <br>Die Royal Academy in London als weitere Station der Ausstellung musste im Zusammenhang mit der Corona-Krise die \u00dcbernahme der Schau absagen. Die Institution ist bis auf Weiteres geschlossen.<\/p>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pressemitteilung Museum Kunstpalast D\u00fcsseldorf, Mai 2020 KUNSTPALASTEhrenhof 4-5, 40479 D\u00fcsseldorfwww.kunstpalast.de Mit \u201eVerr\u00fcckt nach Angelika Kauffmann\u201c widmet der Kunstpalast der ber\u00fchmtesten K\u00fcnstlerin im Zeitalter der Aufkl\u00e4rung und Empfindsamkeit eine gro\u00dfe \u00dcberblicksausstellung. Unter den etwa 100 Gem\u00e4lden, Zeichnungen und Skulpturen werden etliche erstmals \u00f6ffentlich gezeigt. Auch Druckgrafik und Kunsthandwerk nach Motiven der K\u00fcnstlerin lassen eine Zeit aufleben, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":1188,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[125],"tags":[],"class_list":["post-1178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ausstellungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Verr\u00fcckt nach Angelika Kauffmann&quot;verl\u00e4ngert bis20. September 2020 - Der Museumsblog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Verr\u00fcckt nach Angelika Kauffmann&quot;verl\u00e4ngert bis20. September 2020 - Der Museumsblog\" \/>\n<meta property=\"og:description\" content=\"Pressemitteilung Museum Kunstpalast D\u00fcsseldorf, Mai 2020 KUNSTPALASTEhrenhof 4-5, 40479 D\u00fcsseldorfwww.kunstpalast.de Mit \u201eVerr\u00fcckt nach Angelika Kauffmann\u201c widmet der Kunstpalast der ber\u00fchmtesten K\u00fcnstlerin im Zeitalter der Aufkl\u00e4rung und Empfindsamkeit eine gro\u00dfe \u00dcberblicksausstellung. Unter den etwa 100 Gem\u00e4lden, Zeichnungen und Skulpturen werden etliche erstmals \u00f6ffentlich gezeigt. Auch Druckgrafik und Kunsthandwerk nach Motiven der K\u00fcnstlerin lassen eine Zeit aufleben, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Der Museumsblog\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-22T18:39:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-23T20:55:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.museum.de\/blog\/wp-content\/uploads\/2020\/05\/3_-Selbstbildnis-mit-Zeichengriffel-Privatsammlung-1768-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"717\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anna Blume\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\\\/\"},\"author\":{\"name\":\"Anna Blume\",\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/#\\\/schema\\\/person\\\/91a8788095bd8d0794cdd5e92024b083\"},\"headline\":\"&#8222;Verr\u00fcckt nach Angelika Kauffmann&#8220; verl\u00e4ngert bis 20. September 2020\",\"datePublished\":\"2020-05-22T18:39:45+00:00\",\"dateModified\":\"2020-06-23T20:55:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\\\/\"},\"wordCount\":1159,\"publisher\":{\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/3_-Selbstbildnis-mit-Zeichengriffel-Privatsammlung-1768-scaled.jpg\",\"articleSection\":[\"Ausstellungen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\\\/\",\"url\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\\\/\",\"name\":\"\\\"Verr\u00fcckt nach Angelika Kauffmann\\\" verl\u00e4ngert bis 20. September 2020 - Der Museumsblog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/3_-Selbstbildnis-mit-Zeichengriffel-Privatsammlung-1768-scaled.jpg\",\"datePublished\":\"2020-05-22T18:39:45+00:00\",\"dateModified\":\"2020-06-23T20:55:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.museum.de\\\/blog\\\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/3_-Selbstbildnis-mit-Zeichengriffel-Privatsammlung-1768-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/3_-Selbstbildnis-mit-Zeichengriffel-Privatsammlung-1768-scaled.jpg\",\"width\":717,\"height\":1024,\"caption\":\"Angelika Kauffmann, Selbstbildnis mit Zeichengriffel, um 1768 \u00d6l auf Leinwand, 60,8 x 43,4 cm, Privatsammlung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8222;Verr\u00fcckt nach Angelika Kauffmann&#8220;verl\u00e4ngert bis20. September 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/\",\"name\":\"Der Museumsblog\",\"description\":\"Der Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/#organization\"},\"alternateName\":\"museum.de - Der Museumsblog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/#organization\",\"name\":\"Der Museumsblog\",\"url\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/cropped-Audioguide_Titelseite-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/cropped-Audioguide_Titelseite-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Der Museumsblog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/#\\\/schema\\\/person\\\/91a8788095bd8d0794cdd5e92024b083\",\"name\":\"Anna Blume\",\"sameAs\":[\"http:\\\/\\\/cab-annablume.de\"],\"url\":\"https:\\\/\\\/www.museum.de\\\/blog\\\/author\\\/ablume\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Verr\u00fcckt nach Angelika Kauffmann\"verl\u00e4ngert bis20. September 2020 - Der Museumsblog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/","og_locale":"de_DE","og_type":"article","og_title":"\"Verr\u00fcckt nach Angelika Kauffmann\"verl\u00e4ngert bis20. September 2020 - Der Museumsblog","og_description":"Pressemitteilung Museum Kunstpalast D\u00fcsseldorf, Mai 2020 KUNSTPALASTEhrenhof 4-5, 40479 D\u00fcsseldorfwww.kunstpalast.de Mit \u201eVerr\u00fcckt nach Angelika Kauffmann\u201c widmet der Kunstpalast der ber\u00fchmtesten K\u00fcnstlerin im Zeitalter der Aufkl\u00e4rung und Empfindsamkeit eine gro\u00dfe \u00dcberblicksausstellung. Unter den etwa 100 Gem\u00e4lden, Zeichnungen und Skulpturen werden etliche erstmals \u00f6ffentlich gezeigt. Auch Druckgrafik und Kunsthandwerk nach Motiven der K\u00fcnstlerin lassen eine Zeit aufleben, [&hellip;]","og_url":"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/","og_site_name":"Der Museumsblog","article_published_time":"2020-05-22T18:39:45+00:00","article_modified_time":"2020-06-23T20:55:20+00:00","og_image":[{"width":717,"height":1024,"url":"https:\/\/www.museum.de\/blog\/wp-content\/uploads\/2020\/05\/3_-Selbstbildnis-mit-Zeichengriffel-Privatsammlung-1768-scaled.jpg","type":"image\/jpeg"}],"author":"Anna Blume","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/#article","isPartOf":{"@id":"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/"},"author":{"name":"Anna Blume","@id":"https:\/\/www.museum.de\/blog\/#\/schema\/person\/91a8788095bd8d0794cdd5e92024b083"},"headline":"&#8222;Verr\u00fcckt nach Angelika Kauffmann&#8220; verl\u00e4ngert bis 20. September 2020","datePublished":"2020-05-22T18:39:45+00:00","dateModified":"2020-06-23T20:55:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/"},"wordCount":1159,"publisher":{"@id":"https:\/\/www.museum.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.museum.de\/blog\/wp-content\/uploads\/2020\/05\/3_-Selbstbildnis-mit-Zeichengriffel-Privatsammlung-1768-scaled.jpg","articleSection":["Ausstellungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/","url":"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/","name":"\"Verr\u00fcckt nach Angelika Kauffmann\" verl\u00e4ngert bis 20. September 2020 - Der Museumsblog","isPartOf":{"@id":"https:\/\/www.museum.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/#primaryimage"},"image":{"@id":"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.museum.de\/blog\/wp-content\/uploads\/2020\/05\/3_-Selbstbildnis-mit-Zeichengriffel-Privatsammlung-1768-scaled.jpg","datePublished":"2020-05-22T18:39:45+00:00","dateModified":"2020-06-23T20:55:20+00:00","breadcrumb":{"@id":"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/#primaryimage","url":"https:\/\/www.museum.de\/blog\/wp-content\/uploads\/2020\/05\/3_-Selbstbildnis-mit-Zeichengriffel-Privatsammlung-1768-scaled.jpg","contentUrl":"https:\/\/www.museum.de\/blog\/wp-content\/uploads\/2020\/05\/3_-Selbstbildnis-mit-Zeichengriffel-Privatsammlung-1768-scaled.jpg","width":717,"height":1024,"caption":"Angelika Kauffmann, Selbstbildnis mit Zeichengriffel, um 1768 \u00d6l auf Leinwand, 60,8 x 43,4 cm, Privatsammlung"},{"@type":"BreadcrumbList","@id":"https:\/\/www.museum.de\/blog\/verruckt-nach-angelika-kauffmann-30-januar-bis-24-mai-2020-verlangert-bis-12-juli-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.museum.de\/blog\/"},{"@type":"ListItem","position":2,"name":"&#8222;Verr\u00fcckt nach Angelika Kauffmann&#8220;verl\u00e4ngert bis20. September 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.museum.de\/blog\/#website","url":"https:\/\/www.museum.de\/blog\/","name":"Der Museumsblog","description":"Der Blog","publisher":{"@id":"https:\/\/www.museum.de\/blog\/#organization"},"alternateName":"museum.de - Der Museumsblog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.museum.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.museum.de\/blog\/#organization","name":"Der Museumsblog","url":"https:\/\/www.museum.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.museum.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.museum.de\/blog\/wp-content\/uploads\/2019\/03\/cropped-Audioguide_Titelseite-1.jpg","contentUrl":"https:\/\/www.museum.de\/blog\/wp-content\/uploads\/2019\/03\/cropped-Audioguide_Titelseite-1.jpg","width":512,"height":512,"caption":"Der Museumsblog"},"image":{"@id":"https:\/\/www.museum.de\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.museum.de\/blog\/#\/schema\/person\/91a8788095bd8d0794cdd5e92024b083","name":"Anna Blume","sameAs":["http:\/\/cab-annablume.de"],"url":"https:\/\/www.museum.de\/blog\/author\/ablume\/"}]}},"_links":{"self":[{"href":"https:\/\/www.museum.de\/blog\/wp-json\/wp\/v2\/posts\/1178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museum.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.museum.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.museum.de\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museum.de\/blog\/wp-json\/wp\/v2\/comments?post=1178"}],"version-history":[{"count":22,"href":"https:\/\/www.museum.de\/blog\/wp-json\/wp\/v2\/posts\/1178\/revisions"}],"predecessor-version":[{"id":1268,"href":"https:\/\/www.museum.de\/blog\/wp-json\/wp\/v2\/posts\/1178\/revisions\/1268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museum.de\/blog\/wp-json\/wp\/v2\/media\/1188"}],"wp:attachment":[{"href":"https:\/\/www.museum.de\/blog\/wp-json\/wp\/v2\/media?parent=1178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.museum.de\/blog\/wp-json\/wp\/v2\/categories?post=1178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.museum.de\/blog\/wp-json\/wp\/v2\/tags?post=1178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}